{"id":5670,"date":"2022-04-26T20:16:11","date_gmt":"2022-04-26T20:16:11","guid":{"rendered":"https:\/\/aesia.pt\/portal\/?p=5670"},"modified":"2022-04-26T20:16:11","modified_gmt":"2022-04-26T20:16:11","slug":"autoavaliacao-de-agrupamento-inqueritos-caf-online","status":"publish","type":"post","link":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/","title":{"rendered":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5671\" src=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf-300x107.jpg\" alt=\"\" width=\"300\" height=\"107\" srcset=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf-300x107.jpg 300w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf.jpg 397w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online<\/strong><\/em><br \/>\n<em><strong>(Lei n.o 31\/2002, de 20 de dezembro)<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><strong>A todos os elementos da nossa comunidade educativa.<\/strong><\/p>\n<p>Durante o presente ano letivo o AESIA est\u00e1 a implementar um processo de diagn\u00f3stico organizacional e pedag\u00f3gico, envolvendo toda a comunidade educativa \u2013 Aluno(a)s, Encarregado(a)s de Educa\u00e7\u00e3o, Pessoal Docente e Pessoal N\u00e3o Docente. Nesta fase da Autoavalia\u00e7\u00e3o foi adotado o modelo CAF Educa\u00e7\u00e3o (Common Assessment Framework), com a aplica\u00e7\u00e3o de inqu\u00e9ritos online, dirigidos a cada setor da comunidade. Com a vossa colabora\u00e7\u00e3o, pretende-se conhecer os aspetos fundamentais da organiza\u00e7\u00e3o e do funcionamento do Agrupamento, com vista a uma reflex\u00e3o coletiva que identifique os seus pontos fortes e necessidades de melhoria para a constru\u00e7\u00e3o do novo Projeto Educativo. Por isso, o vosso contributo \u00e9 fundamental. Os inqu\u00e9ritos podem ser respondidos entre os dias 26 de abril e 09 de maio e \u00e9 garantida a confidencialidade de todas as respostas. O tratamento estat\u00edstico dos inqu\u00e9ritos \u00e9 da responsabilidade de uma entidade externa ao Agrupamento.<\/p>\n<p>Obrigado pela boa colabora\u00e7\u00e3o de todo(a)s!<\/p>\n<p>Santa Iria de Az\u00f3ia, 26 de abril de 2022<br \/>\nO Diretor, Ivo Cardoso<\/p>\n<p>Acesso:<br \/>\nPara aceder aos inqu\u00e9ritos, deve escolher um dos links:<br \/>\nLink da Educa\u00e7\u00e3o Pr\u00e9-escolar (Educadores, Pessoal N\u00e3o Docente do Pr\u00e9-escolar,<br \/>\nPais\/EE com filhos no Pr\u00e9-escolar e alunos\/crian\u00e7as do Pr\u00e9-escolar e do 1\u00ba e 2\u00ba anos)<br \/>\n<a href=\"https:\/\/survey.mmassociados.pt\/index.php?id=1131\">https:\/\/survey.mmassociados.pt\/index.php?id=1131<\/a><\/p>\n<p>Link do 1o CEB (Pessoal Docente e Pessoal N\u00e3o Docente do 1\u00ba CEB, Pais\/EE com filhos<br \/>\nno 1\u00ba CEB e alunos do 3\u00ba e 4\u00ba anos)<br \/>\n<a href=\"https:\/\/survey.mmassociados.pt\/index.php?id=1132\">https:\/\/survey.mmassociados.pt\/index.php?id=1132<\/a><\/p>\n<p>Link do 2\u00ba e 3\u00ba CEB (Pessoal Docente e Pessoal N\u00e3o Docente do 2\u00ba e 3\u00ba CEB, Pais\/EE<br \/>\ncom filhos no 2\u00ba e 3\u00ba CEB e alunos do 2\u00ba e 3\u00ba CEB)<br \/>\n<a href=\"https:\/\/survey.mmassociados.pt\/index.php?id=1133\">https:\/\/survey.mmassociados.pt\/index.php?id=1133<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online (Lei n.o 31\/2002, de 20 de dezembro) A todos os elementos da nossa&hellip; <a class=\"continue\" href=\"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/\">Ler mais<span> Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":5672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-5670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online &#8211; AESIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online &#8211; AESIA\" \/>\n<meta property=\"og:description\" content=\"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online (Lei n.o 31\/2002, de 20 de dezembro) A todos os elementos da nossa&hellip; Ler mais Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/\" \/>\n<meta property=\"og:site_name\" content=\"AESIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aesia.pt\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T20:16:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"160\" \/>\n\t<meta property=\"og:image:height\" content=\"139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ivo Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivo Cardoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/\"},\"author\":{\"name\":\"Ivo Cardoso\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\"},\"headline\":\"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online\",\"datePublished\":\"2022-04-26T20:16:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Caf1.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/\",\"name\":\"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online &#8211; AESIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Caf1.jpg\",\"datePublished\":\"2022-04-26T20:16:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Caf1.jpg\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Caf1.jpg\",\"width\":160,\"height\":139},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/autoavaliacao-de-agrupamento-inqueritos-caf-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"name\":\"AESIA\",\"description\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"alternateName\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\",\"name\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"alternateName\":\"AESIA\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"width\":162,\"height\":162,\"caption\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aesia.pt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\",\"name\":\"Ivo Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"caption\":\"Ivo Cardoso\"},\"sameAs\":[\"http:\\\/\\\/aesia.pt\"],\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/author\\\/ivo-cardosoaesia-pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online &#8211; AESIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/","og_locale":"pt_PT","og_type":"article","og_title":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online &#8211; AESIA","og_description":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online (Lei n.o 31\/2002, de 20 de dezembro) A todos os elementos da nossa&hellip; Ler mais Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online","og_url":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/","og_site_name":"AESIA","article_publisher":"https:\/\/www.facebook.com\/aesia.pt\/","article_published_time":"2022-04-26T20:16:11+00:00","og_image":[{"width":160,"height":139,"url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf1.jpg","type":"image\/jpeg"}],"author":"Ivo Cardoso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ivo Cardoso","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#article","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/"},"author":{"name":"Ivo Cardoso","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991"},"headline":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online","datePublished":"2022-04-26T20:16:11+00:00","mainEntityOfPage":{"@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/"},"wordCount":320,"publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"image":{"@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf1.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/","url":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/","name":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online &#8211; AESIA","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#primaryimage"},"image":{"@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf1.jpg","datePublished":"2022-04-26T20:16:11+00:00","breadcrumb":{"@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#primaryimage","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf1.jpg","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/04\/Caf1.jpg","width":160,"height":139},{"@type":"BreadcrumbList","@id":"https:\/\/aesia.pt\/portal\/autoavaliacao-de-agrupamento-inqueritos-caf-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aesia.pt\/portal\/"},{"@type":"ListItem","position":2,"name":"Autoavalia\u00e7\u00e3o de Agrupamento \u2013 Inqu\u00e9ritos CAF online"}]},{"@type":"WebSite","@id":"https:\/\/aesia.pt\/portal\/#website","url":"https:\/\/aesia.pt\/portal\/","name":"AESIA","description":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"alternateName":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aesia.pt\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aesia.pt\/portal\/#organization","name":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","alternateName":"AESIA","url":"https:\/\/aesia.pt\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","width":162,"height":162,"caption":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia"},"image":{"@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aesia.pt\/"]},{"@type":"Person","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991","name":"Ivo Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","caption":"Ivo Cardoso"},"sameAs":["http:\/\/aesia.pt"],"url":"https:\/\/aesia.pt\/portal\/author\/ivo-cardosoaesia-pt\/"}]}},"_links":{"self":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/5670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=5670"}],"version-history":[{"count":1,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/5670\/revisions"}],"predecessor-version":[{"id":5673,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/5670\/revisions\/5673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media\/5672"}],"wp:attachment":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=5670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=5670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=5670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}