{"id":5588,"date":"2022-03-17T20:44:32","date_gmt":"2022-03-17T20:44:32","guid":{"rendered":"https:\/\/aesia.pt\/portal\/?p=5588"},"modified":"2022-03-17T20:45:52","modified_gmt":"2022-03-17T20:45:52","slug":"voto-de-pesar","status":"publish","type":"post","link":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/","title":{"rendered":"Voto de Pesar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5591\" src=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg\" alt=\"\" width=\"172\" height=\"119\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O Agrupamento de Escolas de Santa Iria de Az\u00f3ia, vem manifestar o seu mais profundo pesar pelo falecimento da Sr\u00aa Cristina Silva que, com elevado profissionalismo e dedica\u00e7\u00e3o, desempenhou a fun\u00e7\u00e3o de Chefe das Assistentes Operacionais da Escola E.B.2.3. de Santa Iria de Az\u00f3ia, desde o seu in\u00edcio at\u00e9 maio de 2014.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Agrupamento de Escolas de Santa Iria de Az\u00f3ia, vem manifestar o seu mais profundo pesar pelo falecimento da Sr\u00aa&hellip; <a class=\"continue\" href=\"https:\/\/aesia.pt\/portal\/voto-de-pesar\/\">Ler mais<span> Voto de Pesar<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":5591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-5588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voto de Pesar &#8211; AESIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aesia.pt\/portal\/voto-de-pesar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voto de Pesar &#8211; AESIA\" \/>\n<meta property=\"og:description\" content=\"O Agrupamento de Escolas de Santa Iria de Az\u00f3ia, vem manifestar o seu mais profundo pesar pelo falecimento da Sr\u00aa&hellip; Ler mais Voto de Pesar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aesia.pt\/portal\/voto-de-pesar\/\" \/>\n<meta property=\"og:site_name\" content=\"AESIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aesia.pt\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-17T20:44:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-17T20:45:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"172\" \/>\n\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ivo Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivo Cardoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/\"},\"author\":{\"name\":\"Ivo Cardoso\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\"},\"headline\":\"Voto de Pesar\",\"datePublished\":\"2022-03-17T20:44:32+00:00\",\"dateModified\":\"2022-03-17T20:45:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/\"},\"wordCount\":61,\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/luto.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/\",\"name\":\"Voto de Pesar &#8211; AESIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/luto.jpg\",\"datePublished\":\"2022-03-17T20:44:32+00:00\",\"dateModified\":\"2022-03-17T20:45:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/luto.jpg\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/luto.jpg\",\"width\":172,\"height\":119},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/voto-de-pesar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voto de Pesar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"name\":\"AESIA\",\"description\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"alternateName\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\",\"name\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"alternateName\":\"AESIA\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"width\":162,\"height\":162,\"caption\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aesia.pt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\",\"name\":\"Ivo Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"caption\":\"Ivo Cardoso\"},\"sameAs\":[\"http:\\\/\\\/aesia.pt\"],\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/author\\\/ivo-cardosoaesia-pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voto de Pesar &#8211; AESIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/","og_locale":"pt_PT","og_type":"article","og_title":"Voto de Pesar &#8211; AESIA","og_description":"O Agrupamento de Escolas de Santa Iria de Az\u00f3ia, vem manifestar o seu mais profundo pesar pelo falecimento da Sr\u00aa&hellip; Ler mais Voto de Pesar","og_url":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/","og_site_name":"AESIA","article_publisher":"https:\/\/www.facebook.com\/aesia.pt\/","article_published_time":"2022-03-17T20:44:32+00:00","article_modified_time":"2022-03-17T20:45:52+00:00","og_image":[{"width":172,"height":119,"url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg","type":"image\/jpeg"}],"author":"Ivo Cardoso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ivo Cardoso","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#article","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/"},"author":{"name":"Ivo Cardoso","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991"},"headline":"Voto de Pesar","datePublished":"2022-03-17T20:44:32+00:00","dateModified":"2022-03-17T20:45:52+00:00","mainEntityOfPage":{"@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/"},"wordCount":61,"publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"image":{"@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/","url":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/","name":"Voto de Pesar &#8211; AESIA","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#primaryimage"},"image":{"@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg","datePublished":"2022-03-17T20:44:32+00:00","dateModified":"2022-03-17T20:45:52+00:00","breadcrumb":{"@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aesia.pt\/portal\/voto-de-pesar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#primaryimage","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2022\/03\/luto.jpg","width":172,"height":119},{"@type":"BreadcrumbList","@id":"https:\/\/aesia.pt\/portal\/voto-de-pesar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aesia.pt\/portal\/"},{"@type":"ListItem","position":2,"name":"Voto de Pesar"}]},{"@type":"WebSite","@id":"https:\/\/aesia.pt\/portal\/#website","url":"https:\/\/aesia.pt\/portal\/","name":"AESIA","description":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"alternateName":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aesia.pt\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aesia.pt\/portal\/#organization","name":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","alternateName":"AESIA","url":"https:\/\/aesia.pt\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","width":162,"height":162,"caption":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia"},"image":{"@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aesia.pt\/"]},{"@type":"Person","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991","name":"Ivo Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","caption":"Ivo Cardoso"},"sameAs":["http:\/\/aesia.pt"],"url":"https:\/\/aesia.pt\/portal\/author\/ivo-cardosoaesia-pt\/"}]}},"_links":{"self":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/5588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=5588"}],"version-history":[{"count":1,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/5588\/revisions"}],"predecessor-version":[{"id":5592,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/5588\/revisions\/5592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media\/5591"}],"wp:attachment":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=5588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=5588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=5588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}