{"id":3280,"date":"2018-07-02T11:56:21","date_gmt":"2018-07-02T11:56:21","guid":{"rendered":"http:\/\/aesia.pt\/portal\/?p=3280"},"modified":"2023-07-03T21:36:12","modified_gmt":"2023-07-03T21:36:12","slug":"papel-enfermeiro-de-saude-escolar","status":"publish","type":"post","link":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/","title":{"rendered":"Papel do Enfermeiro de Sa\u00fade Escolar"},"content":{"rendered":"<div class=\"gmail_quote\"><\/div>\n<div>\n<p>O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS), que visa a obten\u00e7\u00e3o de ganhos em sa\u00fade atrav\u00e9s da promo\u00e7\u00e3o de contextos escolares favor\u00e1veis \u00e0 sa\u00fade.<\/p>\n<\/div>\n<div><\/div>\n<div class=\"gmail_quote\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RHlSBR5H2x_eoweHKuJk9HFgA_3soms3\/view?usp=sharing\"><b><u>Informa\u00e7\u00e3o sobre o papel do Enfermeiro de Sa\u00fade Escolar<\/u><\/b><\/a><\/div>\n<p><!--codes_iframe--><!--\/codes_iframe--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral&hellip; <a class=\"continue\" href=\"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/\">Ler mais<span> Papel do Enfermeiro de Sa\u00fade Escolar<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":3282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Papel do Enfermeiro de Sa\u00fade Escolar &#8211; AESIA<\/title>\n<meta name=\"description\" content=\"O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papel do Enfermeiro de Sa\u00fade Escolar &#8211; AESIA\" \/>\n<meta property=\"og:description\" content=\"O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"AESIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aesia.pt\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-02T11:56:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-03T21:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2018\/07\/enfermeira.png\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"1009\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ivo Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivo Cardoso\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/\"},\"author\":{\"name\":\"Ivo Cardoso\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\"},\"headline\":\"Papel do Enfermeiro de Sa\u00fade Escolar\",\"datePublished\":\"2018-07-02T11:56:21+00:00\",\"dateModified\":\"2023-07-03T21:36:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/\"},\"wordCount\":68,\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/enfermeira.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/\",\"name\":\"Papel do Enfermeiro de Sa\u00fade Escolar &#8211; AESIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/enfermeira.png\",\"datePublished\":\"2018-07-02T11:56:21+00:00\",\"dateModified\":\"2023-07-03T21:36:12+00:00\",\"description\":\"O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/enfermeira.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/enfermeira.png\",\"width\":607,\"height\":1009},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/papel-enfermeiro-de-saude-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papel do Enfermeiro de Sa\u00fade Escolar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"name\":\"AESIA\",\"description\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"alternateName\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\",\"name\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"alternateName\":\"AESIA\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"width\":162,\"height\":162,\"caption\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aesia.pt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\",\"name\":\"Ivo Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"caption\":\"Ivo Cardoso\"},\"sameAs\":[\"http:\\\/\\\/aesia.pt\"],\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/author\\\/ivo-cardosoaesia-pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papel do Enfermeiro de Sa\u00fade Escolar &#8211; AESIA","description":"O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/","og_locale":"pt_PT","og_type":"article","og_title":"Papel do Enfermeiro de Sa\u00fade Escolar &#8211; AESIA","og_description":"O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS).","og_url":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/","og_site_name":"AESIA","article_publisher":"https:\/\/www.facebook.com\/aesia.pt\/","article_published_time":"2018-07-02T11:56:21+00:00","article_modified_time":"2023-07-03T21:36:12+00:00","og_image":[{"width":607,"height":1009,"url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2018\/07\/enfermeira.png","type":"image\/png"}],"author":"Ivo Cardoso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ivo Cardoso"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#article","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/"},"author":{"name":"Ivo Cardoso","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991"},"headline":"Papel do Enfermeiro de Sa\u00fade Escolar","datePublished":"2018-07-02T11:56:21+00:00","dateModified":"2023-07-03T21:36:12+00:00","mainEntityOfPage":{"@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/"},"wordCount":68,"publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"image":{"@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2018\/07\/enfermeira.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/","url":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/","name":"Papel do Enfermeiro de Sa\u00fade Escolar &#8211; AESIA","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#primaryimage"},"image":{"@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2018\/07\/enfermeira.png","datePublished":"2018-07-02T11:56:21+00:00","dateModified":"2023-07-03T21:36:12+00:00","description":"O enfermeiro de sa\u00fade escolar contribui para a implementa\u00e7\u00e3o do Programa Nacional de Sa\u00fade Escolar (PNSE) emanado pela Dire\u00e7\u00e3o Geral de Sa\u00fade (DGS).","breadcrumb":{"@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#primaryimage","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2018\/07\/enfermeira.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2018\/07\/enfermeira.png","width":607,"height":1009},{"@type":"BreadcrumbList","@id":"https:\/\/aesia.pt\/portal\/papel-enfermeiro-de-saude-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aesia.pt\/portal\/"},{"@type":"ListItem","position":2,"name":"Papel do Enfermeiro de Sa\u00fade Escolar"}]},{"@type":"WebSite","@id":"https:\/\/aesia.pt\/portal\/#website","url":"https:\/\/aesia.pt\/portal\/","name":"AESIA","description":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"alternateName":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aesia.pt\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aesia.pt\/portal\/#organization","name":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","alternateName":"AESIA","url":"https:\/\/aesia.pt\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","width":162,"height":162,"caption":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia"},"image":{"@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aesia.pt\/"]},{"@type":"Person","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991","name":"Ivo Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","caption":"Ivo Cardoso"},"sameAs":["http:\/\/aesia.pt"],"url":"https:\/\/aesia.pt\/portal\/author\/ivo-cardosoaesia-pt\/"}]}},"_links":{"self":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/3280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=3280"}],"version-history":[{"count":4,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/3280\/revisions"}],"predecessor-version":[{"id":8148,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/3280\/revisions\/8148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media\/3282"}],"wp:attachment":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=3280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=3280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=3280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}