{"id":13329,"date":"2024-11-04T08:24:05","date_gmt":"2024-11-04T08:24:05","guid":{"rendered":"https:\/\/aesia.pt\/portal\/?p=13329"},"modified":"2024-11-04T13:21:32","modified_gmt":"2024-11-04T13:21:32","slug":"greve-4-de-novembro","status":"publish","type":"post","link":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/","title":{"rendered":"Actualiza\u00e7\u00e3o Greve &#8211; 4 de novembro"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-1024x768.jpg\" alt=\"\" class=\"wp-image-13338\" srcset=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-1024x768.jpg 1024w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-300x225.jpg 300w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-768x576.jpg 768w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-1536x1152.jpg 1536w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"714\" src=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33-1024x714.jpeg\" alt=\"\" class=\"wp-image-13330\" srcset=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33-1024x714.jpeg 1024w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33-300x209.jpeg 300w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33-768x536.jpeg 768w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33-1536x1072.jpeg 1536w, https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-04-at-08.06.33.jpeg 1697w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Informa\u00e7\u00f5es afixadas no port\u00e3o da EB de Santa Iria de Az\u00f3ia (EB 2\/3).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00f5es afixadas no port\u00e3o da EB de Santa Iria de Az\u00f3ia (EB 2\/3).<\/p>\n","protected":false},"author":13,"featured_media":13338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-13329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualiza\u00e7\u00e3o Greve - 4 de novembro &#8211; AESIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualiza\u00e7\u00e3o Greve - 4 de novembro &#8211; AESIA\" \/>\n<meta property=\"og:description\" content=\"Informa\u00e7\u00f5es afixadas no port\u00e3o da EB de Santa Iria de Az\u00f3ia (EB 2\/3).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/\" \/>\n<meta property=\"og:site_name\" content=\"AESIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aesia.pt\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-04T08:24:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T13:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"noticias@aesia.pt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"noticias@aesia.pt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/\"},\"author\":{\"name\":\"noticias@aesia.pt\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/3e668ee0053d9ab336b3c95d6be37f8e\"},\"headline\":\"Actualiza\u00e7\u00e3o Greve &#8211; 4 de novembro\",\"datePublished\":\"2024-11-04T08:24:05+00:00\",\"dateModified\":\"2024-11-04T13:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/\"},\"wordCount\":21,\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_7034-scaled.jpg\",\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/\",\"name\":\"Actualiza\u00e7\u00e3o Greve - 4 de novembro &#8211; AESIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_7034-scaled.jpg\",\"datePublished\":\"2024-11-04T08:24:05+00:00\",\"dateModified\":\"2024-11-04T13:21:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_7034-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/IMG_7034-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/greve-4-de-novembro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualiza\u00e7\u00e3o Greve &#8211; 4 de novembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"name\":\"AESIA\",\"description\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"alternateName\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\",\"name\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"alternateName\":\"AESIA\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"width\":162,\"height\":162,\"caption\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aesia.pt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/3e668ee0053d9ab336b3c95d6be37f8e\",\"name\":\"noticias@aesia.pt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/303621da1c6d6a06cbd5d2481fab4a901aa14c66676f1edff97ddef8b6cf1319?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/303621da1c6d6a06cbd5d2481fab4a901aa14c66676f1edff97ddef8b6cf1319?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/303621da1c6d6a06cbd5d2481fab4a901aa14c66676f1edff97ddef8b6cf1319?s=96&d=mm&r=g\",\"caption\":\"noticias@aesia.pt\"},\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/author\\\/noticiasaesia-pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualiza\u00e7\u00e3o Greve - 4 de novembro &#8211; AESIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/","og_locale":"pt_PT","og_type":"article","og_title":"Actualiza\u00e7\u00e3o Greve - 4 de novembro &#8211; AESIA","og_description":"Informa\u00e7\u00f5es afixadas no port\u00e3o da EB de Santa Iria de Az\u00f3ia (EB 2\/3).","og_url":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/","og_site_name":"AESIA","article_publisher":"https:\/\/www.facebook.com\/aesia.pt\/","article_published_time":"2024-11-04T08:24:05+00:00","article_modified_time":"2024-11-04T13:21:32+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg","type":"image\/jpeg"}],"author":"noticias@aesia.pt","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"noticias@aesia.pt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#article","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/"},"author":{"name":"noticias@aesia.pt","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/3e668ee0053d9ab336b3c95d6be37f8e"},"headline":"Actualiza\u00e7\u00e3o Greve &#8211; 4 de novembro","datePublished":"2024-11-04T08:24:05+00:00","dateModified":"2024-11-04T13:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/"},"wordCount":21,"publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"image":{"@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg","articleSection":["Destaques"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/","url":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/","name":"Actualiza\u00e7\u00e3o Greve - 4 de novembro &#8211; AESIA","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#primaryimage"},"image":{"@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg","datePublished":"2024-11-04T08:24:05+00:00","dateModified":"2024-11-04T13:21:32+00:00","breadcrumb":{"@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#primaryimage","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/11\/IMG_7034-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/aesia.pt\/portal\/greve-4-de-novembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aesia.pt\/portal\/"},{"@type":"ListItem","position":2,"name":"Actualiza\u00e7\u00e3o Greve &#8211; 4 de novembro"}]},{"@type":"WebSite","@id":"https:\/\/aesia.pt\/portal\/#website","url":"https:\/\/aesia.pt\/portal\/","name":"AESIA","description":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"alternateName":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aesia.pt\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aesia.pt\/portal\/#organization","name":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","alternateName":"AESIA","url":"https:\/\/aesia.pt\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","width":162,"height":162,"caption":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia"},"image":{"@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aesia.pt\/"]},{"@type":"Person","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/3e668ee0053d9ab336b3c95d6be37f8e","name":"noticias@aesia.pt","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/303621da1c6d6a06cbd5d2481fab4a901aa14c66676f1edff97ddef8b6cf1319?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/303621da1c6d6a06cbd5d2481fab4a901aa14c66676f1edff97ddef8b6cf1319?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/303621da1c6d6a06cbd5d2481fab4a901aa14c66676f1edff97ddef8b6cf1319?s=96&d=mm&r=g","caption":"noticias@aesia.pt"},"url":"https:\/\/aesia.pt\/portal\/author\/noticiasaesia-pt\/"}]}},"_links":{"self":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/13329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=13329"}],"version-history":[{"count":3,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/13329\/revisions"}],"predecessor-version":[{"id":13340,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/13329\/revisions\/13340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media\/13338"}],"wp:attachment":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=13329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=13329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=13329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}