{"id":12806,"date":"2024-09-17T16:06:54","date_gmt":"2024-09-17T16:06:54","guid":{"rendered":"http:\/\/aesia.pt\/portal\/?p=12806"},"modified":"2024-09-17T16:06:54","modified_gmt":"2024-09-17T16:06:54","slug":"fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps","status":"publish","type":"post","link":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/","title":{"rendered":"Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)"},"content":{"rendered":"<div class=\"postie-post\">\n<div dir=\"ltr\">\n<div class=\"gmail_quote\">\n<div dir=\"ltr\" class=\"gmail_attr\">&#8212;&#8212;&#8212;- Forwarded message &#8212;&#8212;&#8212;<br \/>De: <strong class=\"gmail_sendername\" dir=\"auto\">Aps<\/strong> <span dir=\"auto\">&lt;<a href=\"mailto:profsintra.formacao@gmail.com\"><a href=\"mailto:profsintra.formacao@gmail.com\" >profsintra.formacao@gmail.com<\/a><\/a>&gt;<\/span><br \/>Date: ter\u00e7a, 17\/09\/2024 \u00e0(s) 10:26<br \/>Subject: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)<br \/>To: <\/div>\n<div dir=\"ltr\">Exmo(a) Sr(a) Diretor(a):<\/p>\n<div>A Associa\u00e7\u00e3o de Professores de Sintra (APS) vem desta forma divulgar o Plano de forma\u00e7\u00e3o (em anexo) de setembro a dezembro de 2024.<\/div>\n<div>Os cursos de forma\u00e7\u00e3o s\u00e3o on-line na plataforma zoom.<\/div>\n<div>A inscri\u00e7\u00e3o \u00e9 feita na p\u00e1gina da APS.<\/div>\n<div>Agradecemos a divulga\u00e7\u00e3o pelos docentes<font color=\"#888888\"><br clear=\"all\"><\/font><\/div>\n<div><\/div>\n<p><span class=\"gmail_signature_prefix\">&#8212; <\/span><\/p>\n<div dir=\"ltr\" class=\"gmail_signature\" data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">Com os melhores cumprimentos<\/p>\n<div><\/div>\n<div>A equipa da APS<\/div>\n<div><font size=\"1\">(Tel: 938782920)<\/font><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"postie-attachments\"><a href=\"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2024\/09\/Setembro-a-Dezembro-2024.pdf\"><img src='https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png' alt='pdf icon' \/> Setembro-a-Dezembro-2024.pdf<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8212;&#8212;&#8212;- Forwarded message &#8212;&#8212;&#8212;De: Aps &lt;profsintra.formacao@gmail.com&gt;Date: ter\u00e7a, 17\/09\/2024 \u00e0(s) 10:26Subject: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)To:&hellip; <a class=\"continue\" href=\"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/\">Ler mais<span> Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-12806","post","type-post","status-publish","format-standard","hentry","category-formacao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fwd: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS) &#8211; AESIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fwd: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS) &#8211; AESIA\" \/>\n<meta property=\"og:description\" content=\"&#8212;&#8212;&#8212;- Forwarded message &#8212;&#8212;&#8212;De: Aps &lt;profsintra.formacao@gmail.com&gt;Date: ter\u00e7a, 17\/09\/2024 \u00e0(s) 10:26Subject: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)To:&hellip; Ler mais Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/\" \/>\n<meta property=\"og:site_name\" content=\"AESIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aesia.pt\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T16:06:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png\" \/>\n<meta name=\"author\" content=\"Ivo Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivo Cardoso\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/\"},\"author\":{\"name\":\"Ivo Cardoso\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\"},\"headline\":\"Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)\",\"datePublished\":\"2024-09-17T16:06:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/\"},\"wordCount\":110,\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/plugins\\\/postie\\\/icons\\\/silver\\\/pdf-48.png\",\"articleSection\":[\"Forma\u00e7\u00e3o\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/\",\"name\":\"Fwd: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS) &#8211; AESIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/plugins\\\/postie\\\/icons\\\/silver\\\/pdf-48.png\",\"datePublished\":\"2024-09-17T16:06:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/plugins\\\/postie\\\/icons\\\/silver\\\/pdf-48.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/plugins\\\/postie\\\/icons\\\/silver\\\/pdf-48.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"name\":\"AESIA\",\"description\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"publisher\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\"},\"alternateName\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#organization\",\"name\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\",\"alternateName\":\"AESIA\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"contentUrl\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo4.png\",\"width\":162,\"height\":162,\"caption\":\"Agrupamento de Escolas de Santa Iria de Az\u00f3ia\"},\"image\":{\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aesia.pt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/#\\\/schema\\\/person\\\/8961c6287f9d82fe320fba91b3e2e991\",\"name\":\"Ivo Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g\",\"caption\":\"Ivo Cardoso\"},\"sameAs\":[\"http:\\\/\\\/aesia.pt\"],\"url\":\"https:\\\/\\\/aesia.pt\\\/portal\\\/author\\\/ivo-cardosoaesia-pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fwd: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS) &#8211; AESIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/","og_locale":"pt_PT","og_type":"article","og_title":"Fwd: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS) &#8211; AESIA","og_description":"&#8212;&#8212;&#8212;- Forwarded message &#8212;&#8212;&#8212;De: Aps &lt;profsintra.formacao@gmail.com&gt;Date: ter\u00e7a, 17\/09\/2024 \u00e0(s) 10:26Subject: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)To:&hellip; Ler mais Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)","og_url":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/","og_site_name":"AESIA","article_publisher":"https:\/\/www.facebook.com\/aesia.pt\/","article_published_time":"2024-09-17T16:06:54+00:00","og_image":[{"url":"https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png","type":"","width":"","height":""}],"author":"Ivo Cardoso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ivo Cardoso"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#article","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/"},"author":{"name":"Ivo Cardoso","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991"},"headline":"Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)","datePublished":"2024-09-17T16:06:54+00:00","mainEntityOfPage":{"@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/"},"wordCount":110,"publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"image":{"@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png","articleSection":["Forma\u00e7\u00e3o"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/","url":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/","name":"Fwd: Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS) &#8211; AESIA","isPartOf":{"@id":"https:\/\/aesia.pt\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#primaryimage"},"image":{"@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#primaryimage"},"thumbnailUrl":"https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png","datePublished":"2024-09-17T16:06:54+00:00","breadcrumb":{"@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#primaryimage","url":"https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/plugins\/postie\/icons\/silver\/pdf-48.png"},{"@type":"BreadcrumbList","@id":"https:\/\/aesia.pt\/portal\/fwd-plano-de-formacao-da-associacao-de-professores-de-sintra-aps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aesia.pt\/portal\/"},{"@type":"ListItem","position":2,"name":"Plano de Forma\u00e7\u00e3o da Associa\u00e7\u00e3o de Professores de Sintra (APS)"}]},{"@type":"WebSite","@id":"https:\/\/aesia.pt\/portal\/#website","url":"https:\/\/aesia.pt\/portal\/","name":"AESIA","description":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","publisher":{"@id":"https:\/\/aesia.pt\/portal\/#organization"},"alternateName":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aesia.pt\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aesia.pt\/portal\/#organization","name":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia","alternateName":"AESIA","url":"https:\/\/aesia.pt\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","contentUrl":"https:\/\/aesia.pt\/portal\/wp-content\/uploads\/2023\/04\/logo4.png","width":162,"height":162,"caption":"Agrupamento de Escolas de Santa Iria de Az\u00f3ia"},"image":{"@id":"https:\/\/aesia.pt\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aesia.pt\/"]},{"@type":"Person","@id":"https:\/\/aesia.pt\/portal\/#\/schema\/person\/8961c6287f9d82fe320fba91b3e2e991","name":"Ivo Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1503fafbe5678f3cfddd3fb093fcb636cd9a58fe5db5256d219059582e42c16?s=96&d=mm&r=g","caption":"Ivo Cardoso"},"sameAs":["http:\/\/aesia.pt"],"url":"https:\/\/aesia.pt\/portal\/author\/ivo-cardosoaesia-pt\/"}]}},"_links":{"self":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/12806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=12806"}],"version-history":[{"count":0,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/posts\/12806\/revisions"}],"wp:attachment":[{"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=12806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=12806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=12806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}